{"id":9636,"date":"2025-02-03T10:17:10","date_gmt":"2025-02-03T13:17:10","guid":{"rendered":"https:\/\/www.panvel.com\/blog\/?p=9636"},"modified":"2025-02-03T10:17:11","modified_gmt":"2025-02-03T13:17:11","slug":"quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo","status":"publish","type":"post","link":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/","title":{"rendered":"Quando devo me preocupar com sinais e pintas no corpo?"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>A pele \u00e9 o maior \u00f3rg\u00e3o do corpo humano e desenvolve diferentes fun\u00e7\u00f5es no nosso organismo. Ao longo da vida, podem surgir sinais, pintas ou manchas, mas alguns aspectos e mudan\u00e7as nesses merecem aten\u00e7\u00e3o especial. Entrevistamos a dermatologista Let\u00edcia Eidt para entender o que observar nesses sinais e pintas para ajudar a identificar poss\u00edveis problemas, como o <strong>c\u00e2ncer de pele<\/strong> ou outras condi\u00e7\u00f5es dermatol\u00f3gicas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Sinais: o que s\u00e3o e como identific\u00e1-los<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p>Sinais ou pintas s\u00e3o les\u00f5es de pele que j\u00e1 podem estar presentes no nascimento ou surgirem ao longo da vida. Eles podem ser de diferentes formatos, cores e tamanhos. Podem ser benignos, como sardas que aparecem devido \u00e0 exposi\u00e7\u00e3o ao sol, e a maioria das pintas. \u201cEntretanto, os sinais e as pintas benignos podem sofrer transforma\u00e7\u00e3o maligna ou j\u00e1 surgirem como les\u00f5es malignas deste o seu in\u00edcio (diferentes tipos de c\u00e2ncer de pele, entre eles, o melanoma)\u201d, explica a dermatologista.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>O que observar em um sinal?<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p>Leticia explica que,&nbsp; para identificar sinais, les\u00f5es ou pintas preocupantes, \u00e9 preciso utilizar a regra do ABCDE, amplamente recomendada por dermatologistas:<\/p>\n\n\n\n<ul>\n<li><strong>A, de Assimetria<\/strong>: um sinal benigno geralmente \u00e9 sim\u00e9trico. Se uma metade for diferente da outra, \u00e9 um alerta.<\/li>\n\n\n\n<li><strong>B, de Bordas<\/strong>: bordas irregulares ou mal definidas tamb\u00e9m podem ser sinais de alerta.<\/li>\n\n\n\n<li><strong>C, de Cor<\/strong>: sinais com v\u00e1rias cores ou que mudam de cor ao longo do tempo precisam ser avaliados.<\/li>\n\n\n\n<li><strong>D, de Di\u00e2metro<\/strong>: pintas ou sinais maiores que 6 mm (aproximadamente o tamanho de uma borracha de l\u00e1pis) podem ser suspeitos.<\/li>\n<\/ul>\n\n\n\n<p><strong>E, de Evolu\u00e7\u00e3o<\/strong>: qualquer mudan\u00e7a no tamanho, forma, cor ou textura de um sinal existente deve ser observada com cuidado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Tipos de les\u00f5es na pele que merecem observa\u00e7\u00e3o<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<ul>\n<li>Pintas (nevos): geralmente s\u00e3o benignas, mas podem sofrer transforma\u00e7\u00e3o maligna. \u00c9 importante monitor\u00e1-las.<br><\/li>\n\n\n\n<li><strong>Manchas senis<\/strong>: surgem nas peles mais claras e sens\u00edveis por exposi\u00e7\u00e3o solar inadequada. Costumam se manifestar em pessoas mais velhas, pois houve ac\u00famulo de dano solar. Tamb\u00e9m merecem acompanhamento dermatol\u00f3gico&nbsp; apesar de benignas, pois indicam que j\u00e1 houve exposi\u00e7\u00e3o solar inadequada. Podem ser mais escuras ou mais claras que o tom de pele.<br><\/li>\n<\/ul>\n\n\n\n<p><strong>Les\u00f5es de pele:<\/strong> quando surgem subitamente e crescem r\u00e1pido, n\u00e3o cicatrizam e sangram.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quando procurar um dermatologista?<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p>Consultas regulares ao dermatologista s\u00e3o a melhor forma de se fazer preven\u00e7\u00e3o, principalmente para quem tem hist\u00f3rico familiar de c\u00e2ncer de pele ou alta exposi\u00e7\u00e3o ao sol. A dermatologista afirma que \u00e9 essencial consultar um dermatologista periodicamente e sempre que voc\u00ea perceber:<br><br>1. Um sinal que atende a um ou mais crit\u00e9rios da regra do ABCDE.<\/p>\n\n\n\n<p>2. Mudan\u00e7as r\u00e1pidas e significativas em um sinal existente.<\/p>\n\n\n\n<p>3. Sinais que sangram, co\u00e7am de forma persistente ou apresentam textura diferente (\u00e1spera e descamativa).&nbsp;4. Qualquer sinal em \u00e1reas de fric\u00e7\u00e3o, como axilas ou planta dos p\u00e9s, que cause desconforto.<\/p>\n\n\n\n<p>\u201cO exame f\u00edsico dermatol\u00f3gico e a dermatoscopia (exame da pele com microsc\u00f3pio de superf\u00edcie) permitem detectar, precocemente, transforma\u00e7\u00f5es malignas de pintas pr\u00e9-existentes ou do c\u00e2ncer de pele na sua forma inicial\u201d, explica Leticia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Preven\u00e7\u00e3o e cuidados di\u00e1rios com a pele<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p>Adotar medidas de prote\u00e7\u00e3o solar e cuidado da pele diariamente \u00e9 importante para evitar o surgimento de <strong>manchas e sinais na pele<\/strong>. Veja algumas dicas:<\/p>\n\n\n\n<ul>\n<li>Use protetor solar com fator de prote\u00e7\u00e3o adequado ao seu tipo de pele<br>Evite exposi\u00e7\u00e3o solar em hor\u00e1rios de pico (10h \u00e0s 16h) e proteja-se na sombra durante esses hor\u00e1rios.<\/li>\n\n\n\n<li>Utilize roupas, bon\u00e9s e chap\u00e9us que tenham protetor solar no seu tecido.<\/li>\n\n\n\n<li>Hidrate-se e mantenha a pele bem hidratada.<\/li>\n\n\n\n<li>Realize autoexames da pele regularmente Embora nem todo sinal e pinta (novo ou antigo) seja motivo de preocupa\u00e7\u00e3o, estar atento \u00e0s mudan\u00e7as na pele \u00e9 essencial para manter a sa\u00fade em dia.<\/li>\n<\/ul>\n\n\n\n<p>Al\u00e9m disso, consultar um dermatologista ao notar altera\u00e7\u00f5es pode fazer toda a diferen\u00e7a na preven\u00e7\u00e3o e no diagn\u00f3stico precoce de condi\u00e7\u00f5es mais graves. Cuide da sua pele e fique atento aos sinais que ela pode estar enviando!&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2025\/01\/Imagem1-e1738262754568.jpg\" alt=\"\" class=\"wp-image-9637\" width=\"249\" height=\"277\" srcset=\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2025\/01\/Imagem1-e1738262754568.jpg 370w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2025\/01\/Imagem1-e1738262754568-269x300.jpg 269w\" sizes=\"(max-width: 249px) 100vw, 249px\" \/><\/figure><\/div>\n\n\n<h2 class=\"wp-block-heading\">Dra. Let\u00edcia Maria Eidt<\/h2>\n\n\n\n<p><\/p>\n\n\n\n<p>M\u00e9dica dermatologista, especialista em Dermatologia pela Sociedade Brasileira de Dermatologia, em Hansenologia pela Sociedade Brasileira de Hansenologia e em Sa\u00fade P\u00fablica pela Escola de Sa\u00fade P\u00fablica do Rio Grande do Sul. Doutora em Gerontologia Biom\u00e9dica pela PUCRS.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saiba identificar diferentes tipos de sinais, o que observar para avaliar sua gravidade e quando procurar um dermatologista.<\/p>\n","protected":false},"author":3,"featured_media":9655,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[2534,31,61,179,1565,419,988,2533],"sponsor":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quando devo me preocupar com sinais e pintas no corpo?<\/title>\n<meta name=\"description\" content=\"Diferentes tipos de sinais, o que observar para avaliar sua gravidade e quando procurar um dermatologista. | Leia mais no Blog Panvel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quando devo me preocupar com sinais e pintas no corpo?\" \/>\n<meta property=\"og:description\" content=\"Diferentes tipos de sinais, o que observar para avaliar sua gravidade e quando procurar um dermatologista. | Leia mais no Blog Panvel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Bem Panvel\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-03T13:17:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-03T13:17:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2025\/02\/Blog-1024x496-Sinais-Corpo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"496\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe Panvel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe Panvel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/\"},\"author\":{\"name\":\"Equipe Panvel\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3\"},\"headline\":\"Quando devo me preocupar com sinais e pintas no corpo?\",\"datePublished\":\"2025-02-03T13:17:10+00:00\",\"dateModified\":\"2025-02-03T13:17:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/\"},\"wordCount\":764,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#organization\"},\"keywords\":[\"autoexame\",\"Bem Estar\",\"C\u00e2ncer de Pele\",\"Cuidados com a sa\u00fade\",\"dermatologista\",\"sa\u00fade\",\"sa\u00fade da pele\",\"sinais na pele\"],\"articleSection\":[\"Rotina de Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/\",\"url\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/\",\"name\":\"Quando devo me preocupar com sinais e pintas no corpo?\",\"isPartOf\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#website\"},\"datePublished\":\"2025-02-03T13:17:10+00:00\",\"dateModified\":\"2025-02-03T13:17:11+00:00\",\"description\":\"Diferentes tipos de sinais, o que observar para avaliar sua gravidade e quando procurar um dermatologista. | Leia mais no Blog Panvel.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.panvel.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rotina de Sa\u00fade\",\"item\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quando devo me preocupar com sinais e pintas no corpo?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#website\",\"url\":\"https:\/\/www.panvel.com\/blog\/\",\"name\":\"Blog Bem Panvel\",\"description\":\"Aqui voc\u00ea encontra conte\u00fados e dicas de sa\u00fade, beleza, bem-estar e muito mais.\",\"publisher\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.panvel.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#organization\",\"name\":\"Panvel Farm\u00e1cias\",\"url\":\"https:\/\/www.panvel.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png\",\"contentUrl\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png\",\"width\":402,\"height\":53,\"caption\":\"Panvel Farm\u00e1cias\"},\"image\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3\",\"name\":\"Equipe Panvel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg\",\"contentUrl\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg\",\"caption\":\"Equipe Panvel\"},\"description\":\"O Blog Bem Panvel conta com uma equipe formada por especialistas e traz para seus leitores conte\u00fados relevantes e de qualidade sobre sa\u00fade, beleza e bem-estar.\",\"url\":\"https:\/\/www.panvel.com\/blog\/author\/dimedmkt\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quando devo me preocupar com sinais e pintas no corpo?","description":"Diferentes tipos de sinais, o que observar para avaliar sua gravidade e quando procurar um dermatologista. | Leia mais no Blog Panvel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/","og_locale":"pt_BR","og_type":"article","og_title":"Quando devo me preocupar com sinais e pintas no corpo?","og_description":"Diferentes tipos de sinais, o que observar para avaliar sua gravidade e quando procurar um dermatologista. | Leia mais no Blog Panvel.","og_url":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/","og_site_name":"Blog Bem Panvel","article_published_time":"2025-02-03T13:17:10+00:00","article_modified_time":"2025-02-03T13:17:11+00:00","og_image":[{"width":1024,"height":496,"url":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2025\/02\/Blog-1024x496-Sinais-Corpo.jpg","type":"image\/jpeg"}],"author":"Equipe Panvel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Equipe Panvel","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/#article","isPartOf":{"@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/"},"author":{"name":"Equipe Panvel","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3"},"headline":"Quando devo me preocupar com sinais e pintas no corpo?","datePublished":"2025-02-03T13:17:10+00:00","dateModified":"2025-02-03T13:17:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/"},"wordCount":764,"commentCount":0,"publisher":{"@id":"https:\/\/www.panvel.com\/blog\/#organization"},"keywords":["autoexame","Bem Estar","C\u00e2ncer de Pele","Cuidados com a sa\u00fade","dermatologista","sa\u00fade","sa\u00fade da pele","sinais na pele"],"articleSection":["Rotina de Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/","url":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/","name":"Quando devo me preocupar com sinais e pintas no corpo?","isPartOf":{"@id":"https:\/\/www.panvel.com\/blog\/#website"},"datePublished":"2025-02-03T13:17:10+00:00","dateModified":"2025-02-03T13:17:11+00:00","description":"Diferentes tipos de sinais, o que observar para avaliar sua gravidade e quando procurar um dermatologista. | Leia mais no Blog Panvel.","breadcrumb":{"@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/quando-devo-me-preocupar-com-sinais-e-pintas-no-corpo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.panvel.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Rotina de Sa\u00fade","item":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/"},{"@type":"ListItem","position":3,"name":"Quando devo me preocupar com sinais e pintas no corpo?"}]},{"@type":"WebSite","@id":"https:\/\/www.panvel.com\/blog\/#website","url":"https:\/\/www.panvel.com\/blog\/","name":"Blog Bem Panvel","description":"Aqui voc\u00ea encontra conte\u00fados e dicas de sa\u00fade, beleza, bem-estar e muito mais.","publisher":{"@id":"https:\/\/www.panvel.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.panvel.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.panvel.com\/blog\/#organization","name":"Panvel Farm\u00e1cias","url":"https:\/\/www.panvel.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png","contentUrl":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png","width":402,"height":53,"caption":"Panvel Farm\u00e1cias"},"image":{"@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3","name":"Equipe Panvel","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg","contentUrl":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg","caption":"Equipe Panvel"},"description":"O Blog Bem Panvel conta com uma equipe formada por especialistas e traz para seus leitores conte\u00fados relevantes e de qualidade sobre sa\u00fade, beleza e bem-estar.","url":"https:\/\/www.panvel.com\/blog\/author\/dimedmkt\/"}]}},"_links":{"self":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts\/9636"}],"collection":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/comments?post=9636"}],"version-history":[{"count":4,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts\/9636\/revisions"}],"predecessor-version":[{"id":9791,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts\/9636\/revisions\/9791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/media\/9655"}],"wp:attachment":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/media?parent=9636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/categories?post=9636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/tags?post=9636"},{"taxonomy":"sponsor","embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/sponsor?post=9636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}