{"id":7798,"date":"2024-04-01T14:55:37","date_gmt":"2024-04-01T17:55:37","guid":{"rendered":"https:\/\/www.panvel.com\/blog\/?p=7798"},"modified":"2024-04-30T11:10:54","modified_gmt":"2024-04-30T14:10:54","slug":"5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar","status":"publish","type":"post","link":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/","title":{"rendered":"Conhe\u00e7a 5 alimentos recomendados para consumir antes de dormir e 5 que voc\u00ea deve evitar!"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>N\u00e3o, voc\u00ea n\u00e3o est\u00e1 proibida(o) de comer algo - \u00e9 o que os nutr\u00f3logos e nutricionistas v\u00e3o dizer. Mas a gente sabe que existem, sim, aqueles alimentos mais leves e aquelas refei\u00e7\u00f5es que pesam mais no est\u00f4mago. E claro que o hor\u00e1rio do dia em que voc\u00ea vai fazer as refei\u00e7\u00f5es interferem na qualidade de vida e no sono.&nbsp;<\/p>\n\n\n\n<p>H\u00e1 quem diga que quem come muito antes de dormir, tem pesadelos. A quest\u00e3o \u00e9: manter uma alimenta\u00e7\u00e3o saud\u00e1vel durante todas as refei\u00e7\u00f5es do dia \u00e9 super importante, mas fazer boas escolhas antes de deitar s\u00e3o fundamentais para ter uma boa noite de sono e at\u00e9 evitar problemas de sa\u00fade.<\/p>\n\n\n\n<p>A maioria dos nutricionistas indica que a \u00faltima refei\u00e7\u00e3o seja feita de 2 a 3 horas antes de dormir, para evitar refluxo ou azia, ou a m\u00e1 digest\u00e3o dos alimentos.&nbsp;<\/p>\n\n\n\n<p>A nutricionista cl\u00ednica e esportiva, Ana Paula Pereira, explica que estudos revelam que fazer a primeira refei\u00e7\u00e3o depois das 9h e a \u00faltima depois das 21h pode causar mais riscos de problemas cardiovasculares.<\/p>\n\n\n\n<p>Ana Paula Pereira defende que, \u00e0s vezes, quando jantamos muito cedo, pode surgir vontade de comer algo mais antes de dormir, mas isso deve ser uma exce\u00e7\u00e3o. \u201cA \u00faltima escolha do dia \u00e9 importante. O problema \u00e9 que voc\u00ea nem sempre escolhe o melhor para voc\u00ea, mas se deixa levar pelo pensamento de que \u2018qualquer coisa serve a essa hora\u2019. Como resultado dessas decis\u00f5es erradas, voc\u00ea pode sentir desconforto digestivo e outros inc\u00f4modos que o impedem de dormir bem\u201d, ressalta.<\/p>\n\n\n\n<p>Por isso, preparamos um top 10:&nbsp;<\/p>\n\n\n\n<p>5 alimentos que voc\u00ea deve evitar e 5 alimentos que voc\u00ea pode comer antes de dormir, para ter uma alimenta\u00e7\u00e3o saud\u00e1vel e dormir de forma mais tranquila.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>5 alimentos que voc\u00ea deve evitar na janta (e porqu\u00ea)<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>1. Pizza<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p>De acordo com a nutricionista Ana Paula Pereira, \u201cal\u00e9m do carboidrato, a massa da pizza tamb\u00e9m \u00e9 rica em gordura, assim como a maioria dos recheios. Comer \u00e0 noite ir\u00e1 implicar em dificuldade para a digest\u00e3o desse alimento. Por isso, o mais recomendado \u00e9 que se coma pizza no hor\u00e1rio do almo\u00e7o, quando o corpo precisa de mais energia para enfrentar o restante do dia\u201d, explica..<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>2. Processados<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p>Alimentos como bacon, frios e industrializados s\u00e3o gordurosos e cont\u00eam muito s\u00f3dio. Eles podem aumentar a tend\u00eancia na reten\u00e7\u00e3o de l\u00edquidos, problemas cardiovasculares e hipertens\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3. Bebidas alco\u00f3licas<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p>Ingerir muito l\u00edquido antes de dormir pode atrapalhar o seu sono,porque voc\u00ea sentir\u00e1 vontade de levantar para ir ao banheiro. J\u00e1 a bebida alc\u00f3olica n\u00e3o \u00e9 recomendada antes de deitar, porque o \u00e1lcool \u00e9 diur\u00e9tico e faz com que o organismo tente eliminar \u00e1gua em excesso, tanto pelo suor quanto pela urina, ou seja, voc\u00ea acordar desidratado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>4. Doces<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p>Os doces, por serem muito cal\u00f3ricos, devem ser evitados. A dica da nutricionista \u00e9: \u201capostar em picol\u00e9s feitos em casa ou uma por\u00e7\u00e3o de fruta, como o abacaxi\u201d, diz.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5. Cafe\u00edna ou termog\u00eanicos<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p>Que o caf\u00e9 tira o sono, voc\u00ea j\u00e1 deve saber. Al\u00e9m dele, bebidas ricas em cafe\u00edna como refrigerantes e alguns ch\u00e1s, como o ch\u00e1 preto e o ch\u00e1 verde, podem continuar agindo no organismo por horas, e podem causar agita\u00e7\u00e3o e ins\u00f4nia. Outros alimentos que devem ser evitados s\u00e3o os termog\u00eanicos como gengibre, canela e pimenta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>5 alimentos que voc\u00ea pode comer \u00e0 noite (e porqu\u00ea)<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>1- Cereais integrais<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p>Os cereais integrais possuem aveia e linha\u00e7a, que s\u00e3o \u00f3timas op\u00e7\u00f5es por serem compostas por carboidratos complexos, o que ajuda na saciedade e n\u00e3o causa picos e quedas bruscas nos n\u00edveis de glicose no&nbsp;<\/p>\n\n\n\n<p>sangue, como os carboidratos. Os cereais devem ser consumidos com modera\u00e7\u00e3o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>2. Vegetais<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p>Os vegetais, como alface, tomate, espinafre, couve-flor, entre outros. Esses alimentos t\u00eam poucas calorias e ajudam a saciar a fome. Al\u00e9m disso, contam com muitas vitaminas e minerais.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>3. Ovos<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p>O ovo \u00e9 uma fonte de prote\u00edna e \u00e9 um dos alimentos considerados mais completos, na nutri\u00e7\u00e3o. Ana Paula destaca que existe um mito de que o ovo poderia fazer mal ao colesterol, mas a verdade \u00e9 que \u201co alimento ajuda muito no colesterol bom, o HDL.\u201d<\/p>\n\n\n\n<p>Algumas sugest\u00f5es de preparo:<\/p>\n\n\n\n<ul>\n<li>Ovos mexidos com azeite de oliva, alho e cebola.<\/li>\n\n\n\n<li>Omelete: batido com cenoura, tomate, espinafre e cebola.<\/li>\n\n\n\n<li>Ovos poch\u00ea: esquente a \u00e1gua, coloque vinagre, fa\u00e7a um redemoinho com a colher e jogue os ovos at\u00e9 cozinharem.<\/li>\n\n\n\n<li>Ovos cozidos regados com azeite de oliva, or\u00e9gano e tempero verde.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>4. Frutas<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p>As frutas podem ser acrecentadas ao jantar. Algumas op\u00e7\u00f5es s\u00e3o: ma\u00e7\u00e3, abacaxi, mam\u00e3o, mel\u00e3o, laranja e abacate. Voc\u00ea pode adicionar uma fonte de fibra, como aveia, linha\u00e7a, chia ou amaranto.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>5. Risoto de arroz 7 gr\u00e3os ou quinoa<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p>A nutricionista destaca que \u201co arroz 7 gr\u00e3os \u00e9 uma fonte de carboidratos de baixo \u00edndice glic\u00eamico, ele possui mais nutrientes, fibras e magn\u00e9sio, melhor digest\u00e3o e mais saciedade que o arroz branco comum puro\u201d, defende.&nbsp;<\/p>\n\n\n\n<p>A sugest\u00e3o de preparo \u00e9 cozinhar o arroz ou quinoa com um pouco de sal, acrescentar shimeji (cogumelo) cortado em uma frigideira com um pouco de \u00e1gua para escaldar. Quando a \u00e1gua secar, acrescente alho, cebola, castanhas do par\u00e1 picadas, sal e azeite. Refogue por 3 minutos e acrescente o refogado \u00e0 quinoa cozida. Depois \u00e9 s\u00f3 servir com tempero verde.<\/p>\n\n\n\n<p>Ana Paula ainda acrescenta que \u00e9 importante planejar o hor\u00e1rio das refei\u00e7\u00f5es e evitar est\u00edmulos e ru\u00eddos durante o per\u00edodo de descanso. \u201cOptar por comidas saud\u00e1veis, e fazer refei\u00e7\u00f5es menores, como frutas, pipoca, palitos de queijo, cereais, iogurtes, vegetais e castanhas. J\u00e1 os alimentos processados, como sorvete, biscoitos e frituras, devem ser evitados\u201d, conclui.<\/p>\n\n\n\n<p>E voc\u00ea, costuma jantar cedo ou tarde? Prefere alimentos mais leves ou a janta \u00e9 sua refei\u00e7\u00e3o favorita? Conta para a gente aqui nos coment\u00e1rios.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2024\/04\/5700-Blog-Semana-da-Saude-1-1024x683.png\" alt=\"\" class=\"wp-image-8008\" srcset=\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2024\/04\/5700-Blog-Semana-da-Saude-1-1024x683.png 1024w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2024\/04\/5700-Blog-Semana-da-Saude-1-300x200.png 300w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2024\/04\/5700-Blog-Semana-da-Saude-1-768x512.png 768w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2024\/04\/5700-Blog-Semana-da-Saude-1-1536x1024.png 1536w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2024\/04\/5700-Blog-Semana-da-Saude-1-2048x1365.png 2048w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2024\/04\/5700-Blog-Semana-da-Saude-1.png 2100w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Sabia que a refei\u00e7\u00e3o que voc\u00ea faz antes de dormir pode influenciar na sua noite de sono? Por isso preparamos essas dicas de quais alimentos comer e quais evitar \u00e0 noite<\/p>\n","protected":false},"author":3,"featured_media":7800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[1865,1866,1863,1869,1870,1864,1867,1862,1868,179,1871],"sponsor":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alimentos recomendados para comer a noite e os que deve evitar!<\/title>\n<meta name=\"description\" content=\"Sabia que a refei\u00e7\u00e3o que voc\u00ea faz antes de dormir pode influenciar na sua noite de sono? | Confira mais no Blog Panvel!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alimentos recomendados para comer a noite e os que deve evitar!\" \/>\n<meta property=\"og:description\" content=\"Sabia que a refei\u00e7\u00e3o que voc\u00ea faz antes de dormir pode influenciar na sua noite de sono? | Confira mais no Blog Panvel!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Bem Panvel\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-01T17:55:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-30T14:10:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2024\/04\/iStock-1305331070.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2121\" \/>\n\t<meta property=\"og:image:height\" content=\"1414\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe Panvel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe Panvel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/\"},\"author\":{\"name\":\"Equipe Panvel\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3\"},\"headline\":\"Conhe\u00e7a 5 alimentos recomendados para consumir antes de dormir e 5 que voc\u00ea deve evitar!\",\"datePublished\":\"2024-04-01T17:55:37+00:00\",\"dateModified\":\"2024-04-30T14:10:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/\"},\"wordCount\":1011,\"commentCount\":8,\"publisher\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#organization\"},\"keywords\":[\"alimentos leve antes de dormir\",\"alimentos leves\",\"alimentos n\u00e3o recomendados antes de dormir\",\"alimentos n\u00e3o saud\u00e1veis\",\"alimentos para dormir bem\",\"alimentos pasados para dormir\",\"alimentos pesados\",\"alimentos recomendados antes de dormir\",\"alimentos saud\u00e1veis\",\"Cuidados com a sa\u00fade\",\"sa\u00fade com alimentos\"],\"articleSection\":[\"Rotina de Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/\",\"url\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/\",\"name\":\"Alimentos recomendados para comer a noite e os que deve evitar!\",\"isPartOf\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#website\"},\"datePublished\":\"2024-04-01T17:55:37+00:00\",\"dateModified\":\"2024-04-30T14:10:54+00:00\",\"description\":\"Sabia que a refei\u00e7\u00e3o que voc\u00ea faz antes de dormir pode influenciar na sua noite de sono? | Confira mais no Blog Panvel!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.panvel.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rotina de Sa\u00fade\",\"item\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conhe\u00e7a 5 alimentos recomendados para consumir antes de dormir e 5 que voc\u00ea deve evitar!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#website\",\"url\":\"https:\/\/www.panvel.com\/blog\/\",\"name\":\"Blog Bem Panvel\",\"description\":\"Aqui voc\u00ea encontra conte\u00fados e dicas de sa\u00fade, beleza, bem-estar e muito mais.\",\"publisher\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.panvel.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#organization\",\"name\":\"Panvel Farm\u00e1cias\",\"url\":\"https:\/\/www.panvel.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png\",\"contentUrl\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png\",\"width\":402,\"height\":53,\"caption\":\"Panvel Farm\u00e1cias\"},\"image\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3\",\"name\":\"Equipe Panvel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg\",\"contentUrl\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg\",\"caption\":\"Equipe Panvel\"},\"description\":\"O Blog Bem Panvel conta com uma equipe formada por especialistas e traz para seus leitores conte\u00fados relevantes e de qualidade sobre sa\u00fade, beleza e bem-estar.\",\"url\":\"https:\/\/www.panvel.com\/blog\/author\/dimedmkt\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alimentos recomendados para comer a noite e os que deve evitar!","description":"Sabia que a refei\u00e7\u00e3o que voc\u00ea faz antes de dormir pode influenciar na sua noite de sono? | Confira mais no Blog Panvel!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/","og_locale":"pt_BR","og_type":"article","og_title":"Alimentos recomendados para comer a noite e os que deve evitar!","og_description":"Sabia que a refei\u00e7\u00e3o que voc\u00ea faz antes de dormir pode influenciar na sua noite de sono? | Confira mais no Blog Panvel!","og_url":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/","og_site_name":"Blog Bem Panvel","article_published_time":"2024-04-01T17:55:37+00:00","article_modified_time":"2024-04-30T14:10:54+00:00","og_image":[{"width":2121,"height":1414,"url":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2024\/04\/iStock-1305331070.jpg","type":"image\/jpeg"}],"author":"Equipe Panvel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Equipe Panvel","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/#article","isPartOf":{"@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/"},"author":{"name":"Equipe Panvel","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3"},"headline":"Conhe\u00e7a 5 alimentos recomendados para consumir antes de dormir e 5 que voc\u00ea deve evitar!","datePublished":"2024-04-01T17:55:37+00:00","dateModified":"2024-04-30T14:10:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/"},"wordCount":1011,"commentCount":8,"publisher":{"@id":"https:\/\/www.panvel.com\/blog\/#organization"},"keywords":["alimentos leve antes de dormir","alimentos leves","alimentos n\u00e3o recomendados antes de dormir","alimentos n\u00e3o saud\u00e1veis","alimentos para dormir bem","alimentos pasados para dormir","alimentos pesados","alimentos recomendados antes de dormir","alimentos saud\u00e1veis","Cuidados com a sa\u00fade","sa\u00fade com alimentos"],"articleSection":["Rotina de Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/","url":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/","name":"Alimentos recomendados para comer a noite e os que deve evitar!","isPartOf":{"@id":"https:\/\/www.panvel.com\/blog\/#website"},"datePublished":"2024-04-01T17:55:37+00:00","dateModified":"2024-04-30T14:10:54+00:00","description":"Sabia que a refei\u00e7\u00e3o que voc\u00ea faz antes de dormir pode influenciar na sua noite de sono? | Confira mais no Blog Panvel!","breadcrumb":{"@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/5-alimentos-recomendados-para-antes-de-dormir-e-5-que-voce-deve-evitar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.panvel.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Rotina de Sa\u00fade","item":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/"},{"@type":"ListItem","position":3,"name":"Conhe\u00e7a 5 alimentos recomendados para consumir antes de dormir e 5 que voc\u00ea deve evitar!"}]},{"@type":"WebSite","@id":"https:\/\/www.panvel.com\/blog\/#website","url":"https:\/\/www.panvel.com\/blog\/","name":"Blog Bem Panvel","description":"Aqui voc\u00ea encontra conte\u00fados e dicas de sa\u00fade, beleza, bem-estar e muito mais.","publisher":{"@id":"https:\/\/www.panvel.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.panvel.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.panvel.com\/blog\/#organization","name":"Panvel Farm\u00e1cias","url":"https:\/\/www.panvel.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png","contentUrl":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png","width":402,"height":53,"caption":"Panvel Farm\u00e1cias"},"image":{"@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3","name":"Equipe Panvel","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg","contentUrl":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg","caption":"Equipe Panvel"},"description":"O Blog Bem Panvel conta com uma equipe formada por especialistas e traz para seus leitores conte\u00fados relevantes e de qualidade sobre sa\u00fade, beleza e bem-estar.","url":"https:\/\/www.panvel.com\/blog\/author\/dimedmkt\/"}]}},"_links":{"self":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts\/7798"}],"collection":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/comments?post=7798"}],"version-history":[{"count":2,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts\/7798\/revisions"}],"predecessor-version":[{"id":8009,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts\/7798\/revisions\/8009"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/media\/7800"}],"wp:attachment":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/media?parent=7798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/categories?post=7798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/tags?post=7798"},{"taxonomy":"sponsor","embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/sponsor?post=7798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}