{"id":6511,"date":"2023-07-06T14:22:58","date_gmt":"2023-07-06T17:22:58","guid":{"rendered":"https:\/\/www.panvel.com\/blog\/?p=6511"},"modified":"2023-07-06T14:22:58","modified_gmt":"2023-07-06T17:22:58","slug":"remedios-caseiros","status":"publish","type":"post","link":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/","title":{"rendered":"Rem\u00e9dios caseiros para gripe e resfriado: cuidados com a sa\u00fade"},"content":{"rendered":"\n<p>Com as mudan\u00e7as de esta\u00e7\u00e3o e, principalmente, a chegada do inverno, as gripes e os resfriados s\u00e3o bastante comuns de aparecerem. E essas condi\u00e7\u00f5es podem prejudicar o bem-estar, por isso, muitos procuram formas de auxiliar na recupera\u00e7\u00e3o, como <strong>rem\u00e9dios caseiros<\/strong>.<\/p>\n\n\n\n<p>Dependendo de cada organismo, os sintomas dessas condi\u00e7\u00f5es de sa\u00fade podem ser mais intensos ou n\u00e3o. Com ajuda dos rem\u00e9dios, \u00e9 poss\u00edvel alivi\u00e1-los durante o tratamento e at\u00e9 acelerar o processo de cura. Mas afinal, quais s\u00e3o eles?<\/p>\n\n\n\n<p>Neste conte\u00fado, voc\u00ea vai descobrir os principais rem\u00e9dios caseiros, suas propriedades, al\u00e9m de alguns cuidados necess\u00e1rios. Acompanhe a leitura at\u00e9 o final!<\/p>\n\n\n\n<p><strong>Voc\u00ea tamb\u00e9m pode ler: <\/strong><a href=\"https:\/\/www.panvel.com\/blog\/panvel-lovers\/cinco-vitaminas-essenciais-para-o-bom-funcionamento-do-organismo-no-inverno\/\"><strong>Cinco vitaminas essenciais para o bom funcionamento do organismo no inverno<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a><\/a>Quais nutrientes est\u00e3o presentes nos rem\u00e9dios caseiros?<\/h2>\n\n\n\n<p>S\u00e3o diversas op\u00e7\u00f5es oferecidas para auxiliar no fortalecimento do sistema imunol\u00f3gico, ajudando na recupera\u00e7\u00e3o de <a href=\"https:\/\/www.panvel.com\/blog\/panvel-clinic\/gripe-h3n2-conheca-os-sintomas-e-como-prevenir-a-doenca\/\"><strong>gripes<\/strong><\/a> e resfriados. No entanto, \u00e9 importante ressaltar que os nutrientes v\u00e3o depender bastante de cada ingrediente utilizado.<\/p>\n\n\n\n<p>Contudo, de modo geral, muitos dos rem\u00e9dios feitos com ingredientes naturais t\u00eam as seguintes propriedades:<\/p>\n\n\n\n<ul>\n<li>vitamina C;<\/li>\n\n\n\n<li>alicina;<\/li>\n\n\n\n<li>propriedades hidratantes;<\/li>\n\n\n\n<li>prote\u00ednas;<\/li>\n\n\n\n<li>carboidratos;<\/li>\n\n\n\n<li>minerais;<\/li>\n\n\n\n<li>entre outros.<\/li>\n<\/ul>\n\n\n\n<p>Cada um deles tem uma determinada fun\u00e7\u00e3o para tratar os sintomas dessas condi\u00e7\u00f5es, causadas por v\u00edrus e outros fatores. Lembre-se que os rem\u00e9dios naturais servem como um complemento para o processo de tratamento.<\/p>\n\n\n\n<p><strong><em>Aten\u00e7\u00e3o! <\/em><\/strong>\u00c9 importante consultar um m\u00e9dico especialista quando apresentar os sintomas. O profissional vai indicar a melhor op\u00e7\u00e3o, conforme a sua condi\u00e7\u00e3o de sa\u00fade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a><\/a>Dicas de rem\u00e9dios caseiros para tratar gripes e resfriados<\/h2>\n\n\n\n<p>Antes de voc\u00ea conhecer mais sobre os <strong>rem\u00e9dios caseiros<\/strong>, \u00e9 fundamental ressaltar que eles n\u00e3o substituem medica\u00e7\u00e3o de farm\u00e1cia e orienta\u00e7\u00e3o m\u00e9dica. Ao perceber os sintomas, procure orienta\u00e7\u00e3o m\u00e9dica.<\/p>\n\n\n\n<p>Quando o corpo fica doente, o nosso<a href=\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/da-pele-ao-sistema-imunologico-9-beneficios-do-consumo-de-agua-para-o-organismo\/\"><strong>sistema imunol\u00f3gico<\/strong><\/a> exige um cuidado maior, como boa alimenta\u00e7\u00e3o, incluindo vitaminas e minerais. Muitos dos rem\u00e9dios caseiros auxiliam no processo de fortalecimento do organismo, principalmente para amenizar os sintomas.<\/p>\n\n\n\n<p>Confira a seguir algumas op\u00e7\u00f5es bastante populares!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a><\/a>Suco de laranja com lim\u00e3o e pr\u00f3polis<\/h3>\n\n\n\n<p>A laranja \u00e9 uma das principais frutas mais utilizadas na prepara\u00e7\u00e3o de rem\u00e9dios caseiros, por ser rica em<a href=\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/confira-dicas-de-como-cuidar-da-imunidade\/\"><strong>vitamina C<\/strong><\/a>. A mistura dos ingredientes fornece uma \u00f3tima solu\u00e7\u00e3o para garantir a boa recupera\u00e7\u00e3o.<\/p>\n\n\n\n<p>O rem\u00e9dio funciona como um antioxidante e anti-inflamat\u00f3rio, que combate o v\u00edrus da gripe no seu organismo. Vale ressaltar que o lim\u00e3o e a laranja s\u00e3o \u00f3timas op\u00e7\u00f5es para fortalecer seu sistema imunol\u00f3gico.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a><\/a>Ch\u00e1 de lim\u00e3o com mel e alho<\/h3>\n\n\n\n<p>Embora o alho n\u00e3o seja um ingrediente favorito para ser consumido cru, ele tem poderosas propriedades medicinais. Ent\u00e3o, misturado com lim\u00e3o e mel, \u00e9 poss\u00edvel garantir um \u00f3timo rem\u00e9dio caseiro.<\/p>\n\n\n\n<p>Al\u00e9m disso, \u00e9 importante ressaltar que o mel tamb\u00e9m auxilia no fortalecimento da imunidade. Por isso, o ch\u00e1 \u00e9 bastante comum entre pacientes com gripe, garantindo o al\u00edvio dos sintomas, principalmente a tosse.<\/p>\n\n\n\n<p>Para usar, basta esmagar o alho e ferv\u00ea-lo com o lim\u00e3o cortado. Em seguida, apenas filtre o ch\u00e1 em uma x\u00edcara, removendo quaisquer resqu\u00edcios de lim\u00e3o e alho. Por fim, despeje uma determinada quantidade de mel na x\u00edcara e misture para tomar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a><\/a>Gengibre com lim\u00e3o<\/h3>\n\n\n\n<p>O gengibre \u00e9 outro ingrediente bastante utilizado para combater gripe ou resfriado, pois \u00e9 composto por<strong> gingerol, vitamina C e zingerona<\/strong>. Essas tr\u00eas propriedades t\u00eam a\u00e7\u00e3o anti-inflamat\u00f3ria, al\u00e9m de antioxidantes.<\/p>\n\n\n\n<p>Com isso, voc\u00ea pode garantir uma recupera\u00e7\u00e3o mais acelerada, aliviando os sintomas de gripe ou resfriado.<\/p>\n\n\n\n<p>Embora ele seja uma \u00f3tima solu\u00e7\u00e3o, \u00e9 fundamental consultar um m\u00e9dico antes de consumir, principalmente as gestantes \u2014 assim, voc\u00ea recebe a orienta\u00e7\u00e3o adequada.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><a><\/a>Ch\u00e1-verde com mel<\/h3>\n\n\n\n<p>Saiba que o mel tamb\u00e9m auxilia no processo de recupera\u00e7\u00e3o. Quando voc\u00ea fica gripado ou resfriado, uma das principais regi\u00f5es afetadas \u00e9 a garganta. O mel ajuda na redu\u00e7\u00e3o da inflama\u00e7\u00e3o, diminuindo tosse e at\u00e9 mesmo catarro.<\/p>\n\n\n\n<p>O ch\u00e1-verde \u00e9 uma \u00f3tima op\u00e7\u00e3o para fortalecer o sistema imunol\u00f3gico, por oferecer propriedades<strong> anti-inflamat\u00f3rias e antioxidantes<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><a><\/a>Cuidados necess\u00e1rios com rem\u00e9dios caseiros<\/h2>\n\n\n\n<p>Como mencionamos, embora os rem\u00e9dios caseiros tenham muitos pontos positivos no combate \u00e0s gripes e resfriados, \u00e9 fundamental consultar um m\u00e9dico antes de tom\u00e1-los. Isso porque existem algumas contraindica\u00e7\u00f5es para determinados ingredientes.<\/p>\n\n\n\n<p>De modo geral, confira alguns cuidados necess\u00e1rios!<\/p>\n\n\n\n<ul>\n<li>Evite tomar qualquer rem\u00e9dio sem acompanhamento m\u00e9dico;<\/li>\n\n\n\n<li>Mulheres gr\u00e1vidas precisam consultar seu m\u00e9dico;<\/li>\n\n\n\n<li>Aten\u00e7\u00e3o na hora de dar algum tipo de rem\u00e9dio para as crian\u00e7as;<\/li>\n\n\n\n<li>D\u00ea aten\u00e7\u00e3o \u00e0s propriedades dos ingredientes;<\/li>\n\n\n\n<li>Entre outros cuidados.<\/li>\n<\/ul>\n\n\n\n<p>Os rem\u00e9dios caseiros trazem diversos benef\u00edcios \u00e0 nossa sa\u00fade, principalmente na hora de garantir o bem-estar dos organismos. S\u00e3o diversas op\u00e7\u00f5es para voc\u00ea escolher, o ideal \u00e9 analisar bem sua necessidade para utiliz\u00e1-los.<\/p>\n\n\n\n<p><strong>Curtiu essas dicas?<\/strong> Esperamos que sim! Agora que voc\u00ea j\u00e1 conhece mais sobre o assunto, que tal saber como garantir a sa\u00fade das crian\u00e7as no inverno? Ent\u00e3o, acesse o blog da <strong>Panvel<\/strong> e descubra <a href=\"https:\/\/www.panvel.com\/blog\/bebe-e-crianca\/como-evitar-que-as-criancas-tenham-doencas-respiratorias\/\"><strong>como evitar que as crian\u00e7as tenham doen\u00e7as respirat\u00f3rias<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entenda como os rem\u00e9dios caseiros podem auxiliar na recupera\u00e7\u00e3o de condi\u00e7\u00f5es como gripes ou resfriados. Acesse para conferir! <\/p>\n","protected":false},"author":3,"featured_media":6512,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[1187,1183,421,1184,1186,107,1182,1185,1180,1181],"sponsor":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rem\u00e9dios caseiros para gripe e resfriado: cuidados com a sa\u00fade<\/title>\n<meta name=\"description\" content=\"Entenda como os rem\u00e9dios caseiros podem auxiliar na recupera\u00e7\u00e3o de condi\u00e7\u00f5es como gripes ou resfriados. Acesse para conferir!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rem\u00e9dios caseiros para gripe e resfriado: cuidados com a sa\u00fade\" \/>\n<meta property=\"og:description\" content=\"Entenda como os rem\u00e9dios caseiros podem auxiliar na recupera\u00e7\u00e3o de condi\u00e7\u00f5es como gripes ou resfriados. Acesse para conferir!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Bem Panvel\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-06T17:22:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2023\/07\/iStock-1005735732.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"724\" \/>\n\t<meta property=\"og:image:height\" content=\"483\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe Panvel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe Panvel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/\"},\"author\":{\"name\":\"Equipe Panvel\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3\"},\"headline\":\"Rem\u00e9dios caseiros para gripe e resfriado: cuidados com a sa\u00fade\",\"datePublished\":\"2023-07-06T17:22:58+00:00\",\"dateModified\":\"2023-07-06T17:22:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/\"},\"wordCount\":906,\"commentCount\":14,\"publisher\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#organization\"},\"keywords\":[\"Ch\u00e1 de lim\u00e3o com mel e alho\",\"ch\u00e1-verde com mel\",\"Ch\u00e1s\",\"gengibre\",\"gengibre com lim\u00e3o\",\"Gripe\",\"gripe e resfriado\",\"lim\u00e3o\",\"rem\u00e9dios caseiros para gripe\",\"rem\u00e9dios caseiros para resfriado\"],\"articleSection\":[\"Rotina de Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/\",\"url\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/\",\"name\":\"Rem\u00e9dios caseiros para gripe e resfriado: cuidados com a sa\u00fade\",\"isPartOf\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#website\"},\"datePublished\":\"2023-07-06T17:22:58+00:00\",\"dateModified\":\"2023-07-06T17:22:58+00:00\",\"description\":\"Entenda como os rem\u00e9dios caseiros podem auxiliar na recupera\u00e7\u00e3o de condi\u00e7\u00f5es como gripes ou resfriados. Acesse para conferir!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.panvel.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rotina de Sa\u00fade\",\"item\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rem\u00e9dios caseiros para gripe e resfriado: cuidados com a sa\u00fade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#website\",\"url\":\"https:\/\/www.panvel.com\/blog\/\",\"name\":\"Blog Bem Panvel\",\"description\":\"Aqui voc\u00ea encontra conte\u00fados e dicas de sa\u00fade, beleza, bem-estar e muito mais.\",\"publisher\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.panvel.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#organization\",\"name\":\"Panvel Farm\u00e1cias\",\"url\":\"https:\/\/www.panvel.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png\",\"contentUrl\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png\",\"width\":402,\"height\":53,\"caption\":\"Panvel Farm\u00e1cias\"},\"image\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3\",\"name\":\"Equipe Panvel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg\",\"contentUrl\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg\",\"caption\":\"Equipe Panvel\"},\"description\":\"O Blog Bem Panvel conta com uma equipe formada por especialistas e traz para seus leitores conte\u00fados relevantes e de qualidade sobre sa\u00fade, beleza e bem-estar.\",\"url\":\"https:\/\/www.panvel.com\/blog\/author\/dimedmkt\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rem\u00e9dios caseiros para gripe e resfriado: cuidados com a sa\u00fade","description":"Entenda como os rem\u00e9dios caseiros podem auxiliar na recupera\u00e7\u00e3o de condi\u00e7\u00f5es como gripes ou resfriados. Acesse para conferir!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/","og_locale":"pt_BR","og_type":"article","og_title":"Rem\u00e9dios caseiros para gripe e resfriado: cuidados com a sa\u00fade","og_description":"Entenda como os rem\u00e9dios caseiros podem auxiliar na recupera\u00e7\u00e3o de condi\u00e7\u00f5es como gripes ou resfriados. Acesse para conferir!","og_url":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/","og_site_name":"Blog Bem Panvel","article_published_time":"2023-07-06T17:22:58+00:00","og_image":[{"width":724,"height":483,"url":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2023\/07\/iStock-1005735732.jpg","type":"image\/jpeg"}],"author":"Equipe Panvel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Equipe Panvel","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/#article","isPartOf":{"@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/"},"author":{"name":"Equipe Panvel","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3"},"headline":"Rem\u00e9dios caseiros para gripe e resfriado: cuidados com a sa\u00fade","datePublished":"2023-07-06T17:22:58+00:00","dateModified":"2023-07-06T17:22:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/"},"wordCount":906,"commentCount":14,"publisher":{"@id":"https:\/\/www.panvel.com\/blog\/#organization"},"keywords":["Ch\u00e1 de lim\u00e3o com mel e alho","ch\u00e1-verde com mel","Ch\u00e1s","gengibre","gengibre com lim\u00e3o","Gripe","gripe e resfriado","lim\u00e3o","rem\u00e9dios caseiros para gripe","rem\u00e9dios caseiros para resfriado"],"articleSection":["Rotina de Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/","url":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/","name":"Rem\u00e9dios caseiros para gripe e resfriado: cuidados com a sa\u00fade","isPartOf":{"@id":"https:\/\/www.panvel.com\/blog\/#website"},"datePublished":"2023-07-06T17:22:58+00:00","dateModified":"2023-07-06T17:22:58+00:00","description":"Entenda como os rem\u00e9dios caseiros podem auxiliar na recupera\u00e7\u00e3o de condi\u00e7\u00f5es como gripes ou resfriados. Acesse para conferir!","breadcrumb":{"@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/remedios-caseiros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.panvel.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Rotina de Sa\u00fade","item":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/"},{"@type":"ListItem","position":3,"name":"Rem\u00e9dios caseiros para gripe e resfriado: cuidados com a sa\u00fade"}]},{"@type":"WebSite","@id":"https:\/\/www.panvel.com\/blog\/#website","url":"https:\/\/www.panvel.com\/blog\/","name":"Blog Bem Panvel","description":"Aqui voc\u00ea encontra conte\u00fados e dicas de sa\u00fade, beleza, bem-estar e muito mais.","publisher":{"@id":"https:\/\/www.panvel.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.panvel.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.panvel.com\/blog\/#organization","name":"Panvel Farm\u00e1cias","url":"https:\/\/www.panvel.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png","contentUrl":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png","width":402,"height":53,"caption":"Panvel Farm\u00e1cias"},"image":{"@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3","name":"Equipe Panvel","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg","contentUrl":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg","caption":"Equipe Panvel"},"description":"O Blog Bem Panvel conta com uma equipe formada por especialistas e traz para seus leitores conte\u00fados relevantes e de qualidade sobre sa\u00fade, beleza e bem-estar.","url":"https:\/\/www.panvel.com\/blog\/author\/dimedmkt\/"}]}},"_links":{"self":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts\/6511"}],"collection":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/comments?post=6511"}],"version-history":[{"count":1,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts\/6511\/revisions"}],"predecessor-version":[{"id":6513,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts\/6511\/revisions\/6513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/media\/6512"}],"wp:attachment":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/media?parent=6511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/categories?post=6511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/tags?post=6511"},{"taxonomy":"sponsor","embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/sponsor?post=6511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}