{"id":4373,"date":"2022-04-07T08:29:35","date_gmt":"2022-04-07T11:29:35","guid":{"rendered":"\/blog\/?p=4373"},"modified":"2026-02-06T13:57:18","modified_gmt":"2026-02-06T16:57:18","slug":"dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel","status":"publish","type":"post","link":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/","title":{"rendered":"Dia Mundial da Sa\u00fade: confira dicas para ter uma vida saud\u00e1vel e de qualidade"},"content":{"rendered":"\n<p>Quando falamos em sa\u00fade, pensamos em quest\u00f5es como ir ao m\u00e9dico e realizar exames para n\u00e3o ficarmos doentes. No entanto, sa\u00fade n\u00e3o \u00e9 apenas o oposto de doen\u00e7a. A Organiza\u00e7\u00e3o Mundial da Sa\u00fade (OMS) definiu o conceito de sa\u00fade como \u201cum estado de completo bem-estar f\u00edsico, mental e social e n\u00e3o apenas a aus\u00eancia de doen\u00e7a\u201d.<\/p>\n\n\n\n<p>Para ter sa\u00fade, \u00e9 preciso ter cuidados espec\u00edficos, que v\u00e3o muito al\u00e9m de ir ao m\u00e9dico somente quando estamos com alguma condi\u00e7\u00e3o. Para ter uma vida longeva e de qualidade, \u00e9 importante olhar para in\u00fameros fatores que possam comprometer sua sa\u00fade f\u00edsica, mental e nutricional, e mudar h\u00e1bitos de vida.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pensando nisso, neste dia 7 de abril, separamos algumas dicas para voc\u00ea cuidar mais da sua sa\u00fade e bem-estar.<\/strong><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Sa\u00fade f\u00edsica<\/strong><\/h3>\n\n\n\n<p>Para verificar se est\u00e1 tudo em ordem com a sa\u00fade do seu corpo, \u00e9 importante realizar anualmente um check-up de exames necess\u00e1rios. A medida, que tem como principal objetivo a preven\u00e7\u00e3o, \u00e9 capaz de auxiliar na detec\u00e7\u00e3o precoce de doen\u00e7as, contribuindo para um tratamento e cura mais efetivos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Sa\u00fade mental<\/strong><\/h3>\n\n\n\n<p>Voc\u00ea certamente j\u00e1 ouviu a frase \u201cmente s\u00e3, corpo s\u00e3o\u201d. Isso porque n\u00e3o basta cuidarmos apenas da sa\u00fade f\u00edsica, \u00e9 preciso estarmos atentos aos cuidados da nossa mente, que muitas vezes n\u00e3o priorizamos ou deixamos passar despercebida.&nbsp;<\/p>\n\n\n\n<p>A psicoterapia promove benef\u00edcios que envolvem diversos \u00e2mbitos de nossas vidas, como quest\u00f5es emocionais, afetivas, familiares, comportamentais, sociais e profissionais.<\/p>\n\n\n\n<p>Manter as sess\u00f5es de terapia em dia reduz a ansiedade e estresse, auxiliando no tratamento da depress\u00e3o, contribui para a melhora da autoestima, do autoconhecimento, crescimento pessoal, al\u00e9m do desenvolvimento de novas habilidades emocionais, cognitivas e comportamentais, por exemplo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Atividades f\u00edsicas<\/strong><\/h3>\n\n\n\n<p>Cuidar do corpo tamb\u00e9m exige a pr\u00e1tica regular de atividades f\u00edsicas. A OMS recomenda que uma pessoa adulta realize pelo menos 150 a 300 minutos de atividade aer\u00f3bica moderada a vigorosa por semana, incluindo aquelas com doen\u00e7as cr\u00f4nicas ou incapacidade, e de 75 a 150 minutos por semana para atividades f\u00edsicas de n\u00edvel intenso.<\/p>\n\n\n\n<p>A pr\u00e1tica de exerc\u00edcios f\u00edsicos traz in\u00fameros benef\u00edcios para a sa\u00fade, prevenindo diversas doen\u00e7as, como hipertens\u00e3o, doen\u00e7as cardiovasculares, respirat\u00f3rias a reum\u00e1ticas, colesterol e obesidade. Al\u00e9m disso, a pr\u00e1tica contribui para a perda de gordura corporal, melhora a circula\u00e7\u00e3o sangu\u00ednea, o sistema imunol\u00f3gico, a respira\u00e7\u00e3o e a mem\u00f3ria, aumenta a autoestima e fornece a sensa\u00e7\u00e3o de bem-estar e disposi\u00e7\u00e3o.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Alimenta\u00e7\u00e3o saud\u00e1vel<\/strong><\/h3>\n\n\n\n<p>A alimenta\u00e7\u00e3o saud\u00e1vel aliada a pr\u00e1tica de exerc\u00edcios f\u00edsicos \u00e9 fundamental para manter o pleno funcionamento do organismo. Para ter uma dieta saud\u00e1vel, \u00e9 preciso incluir alimentos naturais ou minimamente processados no card\u00e1pio, como frutas, legumes, verduras, gr\u00e3os, cereais integrais, oleaginosas, prote\u00ednas, entre outros. Esses alimentos, que podem ser encontrados em grandes quantidades, proporcionam os nutrientes necess\u00e1rios para a manuten\u00e7\u00e3o da sa\u00fade.<\/p>\n\n\n\n<p>Mas n\u00e3o esque\u00e7a de buscar o acompanhamento com o profissional nutricionista. A ajuda profissional \u00e9 essencial, uma vez que o nutricionista ser\u00e1 respons\u00e1vel por tra\u00e7ar um plano alimentar de acordo com as suas necessidades.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Autocuidado<\/strong><\/h3>\n\n\n\n<p>O autocuidado \u00e9 fundamental, e deve ser praticado todos os dias. O autocuidado \u00e9 um conjunto de a\u00e7\u00f5es relacionadas ao bem-estar pr\u00f3prio que traz benef\u00edcios ao corpo e \u00e0 sa\u00fade. \u00c9 prestar aten\u00e7\u00e3o nos sinais que seu corpo d\u00e1, al\u00e9m de entender suas necessidades.<\/p>\n\n\n\n<p>Para al\u00e9m dos cuidados com a sa\u00fade f\u00edsica, mental e nutricional, \u00e9 preciso olhar para si e buscar preencher sua vida com coisas que proporcionam bem-estar. Desse modo, tire um tempo para fazer o que voc\u00ea gosta, como passear no parque, ouvir sua m\u00fasica favorita, ver um filme, ler um bom livro ou ver os amigos e familiares.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Dia Mundial da Sa\u00fade 2022<\/strong><\/h3>\n\n\n\n<p>Celebrado anualmente no dia 7 de abril, o Dia Mundial da Sa\u00fade tem por objetivo discutir temas que englobam a promo\u00e7\u00e3o da qualidade de vida, conscientizando a popula\u00e7\u00e3o mundial sobre a import\u00e2ncia da preven\u00e7\u00e3o e preserva\u00e7\u00e3o da sa\u00fade. A data foi criada pela Organiza\u00e7\u00e3o Mundial da Sa\u00fade em 1948, e passou a ser celebrada todos os anos em 1950.<\/p>\n\n\n\n<p>Neste ano, a data carrega o tema \"Nosso planeta, nossa sa\u00fade\". De acordo com a Organiza\u00e7\u00e3o, o tema foi definido em decorr\u00eancia do atual cen\u00e1rio de pandemia, al\u00e9m da polui\u00e7\u00e3o do planeta e incid\u00eancia crescente de doen\u00e7as.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Al\u00e9m de todos esses cuidados com a sa\u00fade, o\u00a0<a href=\"https:\/\/www.panvel.com\/panvel\/clinic\/home\">Panvel Clinic<\/a> traz esse jeito de cuidar e proporcionar servi\u00e7os de qualidade, efici\u00eancia e import\u00e2ncia, pensando no bem-estar das pessoas. <\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fa\u00e7a dos cuidados com a sa\u00fade um h\u00e1bito, cuide de voc\u00ea todos os dias; confira dicas para manter uma vida saud\u00e1vel e de qualidade.<\/p>\n","protected":false},"author":3,"featured_media":4376,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[41,31,29,179,464,15,80,20],"sponsor":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dia Mundial da Sa\u00fade: confira dicas para ter uma vida saud\u00e1vel e de qualidade | Blog Bem Panvel<\/title>\n<meta name=\"description\" content=\"Fa\u00e7a dos cuidados com a sa\u00fade um h\u00e1bito, cuide de voc\u00ea todos os dias; confira dicas para manter uma vida saud\u00e1vel e de qualidade.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dia Mundial da Sa\u00fade: confira dicas para ter uma vida saud\u00e1vel e de qualidade | Blog Bem Panvel\" \/>\n<meta property=\"og:description\" content=\"Fa\u00e7a dos cuidados com a sa\u00fade um h\u00e1bito, cuide de voc\u00ea todos os dias; confira dicas para manter uma vida saud\u00e1vel e de qualidade.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Bem Panvel\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-07T11:29:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T16:57:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/04\/iStock-1319764588-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"724\" \/>\n\t<meta property=\"og:image:height\" content=\"483\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe Panvel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe Panvel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/\"},\"author\":{\"name\":\"Equipe Panvel\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3\"},\"headline\":\"Dia Mundial da Sa\u00fade: confira dicas para ter uma vida saud\u00e1vel e de qualidade\",\"datePublished\":\"2022-04-07T11:29:35+00:00\",\"dateModified\":\"2026-02-06T16:57:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/\"},\"wordCount\":835,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#organization\"},\"keywords\":[\"Alimenta\u00e7\u00e3o\",\"Bem Estar\",\"Cuidados com a Pele\",\"Cuidados com a sa\u00fade\",\"Cuidados do Dia a dia\",\"Dicas\",\"Panvel Clinic\",\"Preven\u00e7\u00e3o\"],\"articleSection\":[\"Rotina de Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/\",\"url\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/\",\"name\":\"Dia Mundial da Sa\u00fade: confira dicas para ter uma vida saud\u00e1vel e de qualidade | Blog Bem Panvel\",\"isPartOf\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#website\"},\"datePublished\":\"2022-04-07T11:29:35+00:00\",\"dateModified\":\"2026-02-06T16:57:18+00:00\",\"description\":\"Fa\u00e7a dos cuidados com a sa\u00fade um h\u00e1bito, cuide de voc\u00ea todos os dias; confira dicas para manter uma vida saud\u00e1vel e de qualidade.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.panvel.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rotina de Sa\u00fade\",\"item\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dia Mundial da Sa\u00fade: confira dicas para ter uma vida saud\u00e1vel e de qualidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#website\",\"url\":\"https:\/\/www.panvel.com\/blog\/\",\"name\":\"Blog Bem Panvel\",\"description\":\"Aqui voc\u00ea encontra conte\u00fados e dicas de sa\u00fade, beleza, bem-estar e muito mais.\",\"publisher\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.panvel.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#organization\",\"name\":\"Panvel Farm\u00e1cias\",\"url\":\"https:\/\/www.panvel.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png\",\"contentUrl\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png\",\"width\":402,\"height\":53,\"caption\":\"Panvel Farm\u00e1cias\"},\"image\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3\",\"name\":\"Equipe Panvel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg\",\"contentUrl\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg\",\"caption\":\"Equipe Panvel\"},\"description\":\"O Blog Bem Panvel conta com uma equipe formada por especialistas e traz para seus leitores conte\u00fados relevantes e de qualidade sobre sa\u00fade, beleza e bem-estar.\",\"url\":\"https:\/\/www.panvel.com\/blog\/author\/dimedmkt\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dia Mundial da Sa\u00fade: confira dicas para ter uma vida saud\u00e1vel e de qualidade | Blog Bem Panvel","description":"Fa\u00e7a dos cuidados com a sa\u00fade um h\u00e1bito, cuide de voc\u00ea todos os dias; confira dicas para manter uma vida saud\u00e1vel e de qualidade.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/","og_locale":"pt_BR","og_type":"article","og_title":"Dia Mundial da Sa\u00fade: confira dicas para ter uma vida saud\u00e1vel e de qualidade | Blog Bem Panvel","og_description":"Fa\u00e7a dos cuidados com a sa\u00fade um h\u00e1bito, cuide de voc\u00ea todos os dias; confira dicas para manter uma vida saud\u00e1vel e de qualidade.","og_url":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/","og_site_name":"Blog Bem Panvel","article_published_time":"2022-04-07T11:29:35+00:00","article_modified_time":"2026-02-06T16:57:18+00:00","og_image":[{"width":724,"height":483,"url":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/04\/iStock-1319764588-1-1.jpg","type":"image\/jpeg"}],"author":"Equipe Panvel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Equipe Panvel","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/#article","isPartOf":{"@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/"},"author":{"name":"Equipe Panvel","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3"},"headline":"Dia Mundial da Sa\u00fade: confira dicas para ter uma vida saud\u00e1vel e de qualidade","datePublished":"2022-04-07T11:29:35+00:00","dateModified":"2026-02-06T16:57:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/"},"wordCount":835,"commentCount":0,"publisher":{"@id":"https:\/\/www.panvel.com\/blog\/#organization"},"keywords":["Alimenta\u00e7\u00e3o","Bem Estar","Cuidados com a Pele","Cuidados com a sa\u00fade","Cuidados do Dia a dia","Dicas","Panvel Clinic","Preven\u00e7\u00e3o"],"articleSection":["Rotina de Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/","url":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/","name":"Dia Mundial da Sa\u00fade: confira dicas para ter uma vida saud\u00e1vel e de qualidade | Blog Bem Panvel","isPartOf":{"@id":"https:\/\/www.panvel.com\/blog\/#website"},"datePublished":"2022-04-07T11:29:35+00:00","dateModified":"2026-02-06T16:57:18+00:00","description":"Fa\u00e7a dos cuidados com a sa\u00fade um h\u00e1bito, cuide de voc\u00ea todos os dias; confira dicas para manter uma vida saud\u00e1vel e de qualidade.","breadcrumb":{"@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/dia-mundial-da-saude-e-os-cuidados-para-ter-uma-vida-saudavel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.panvel.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Rotina de Sa\u00fade","item":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/"},{"@type":"ListItem","position":3,"name":"Dia Mundial da Sa\u00fade: confira dicas para ter uma vida saud\u00e1vel e de qualidade"}]},{"@type":"WebSite","@id":"https:\/\/www.panvel.com\/blog\/#website","url":"https:\/\/www.panvel.com\/blog\/","name":"Blog Bem Panvel","description":"Aqui voc\u00ea encontra conte\u00fados e dicas de sa\u00fade, beleza, bem-estar e muito mais.","publisher":{"@id":"https:\/\/www.panvel.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.panvel.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.panvel.com\/blog\/#organization","name":"Panvel Farm\u00e1cias","url":"https:\/\/www.panvel.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png","contentUrl":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png","width":402,"height":53,"caption":"Panvel Farm\u00e1cias"},"image":{"@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3","name":"Equipe Panvel","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg","contentUrl":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg","caption":"Equipe Panvel"},"description":"O Blog Bem Panvel conta com uma equipe formada por especialistas e traz para seus leitores conte\u00fados relevantes e de qualidade sobre sa\u00fade, beleza e bem-estar.","url":"https:\/\/www.panvel.com\/blog\/author\/dimedmkt\/"}]}},"_links":{"self":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts\/4373"}],"collection":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/comments?post=4373"}],"version-history":[{"count":6,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts\/4373\/revisions"}],"predecessor-version":[{"id":10660,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts\/4373\/revisions\/10660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/media\/4376"}],"wp:attachment":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/media?parent=4373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/categories?post=4373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/tags?post=4373"},{"taxonomy":"sponsor","embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/sponsor?post=4373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}