{"id":2866,"date":"2021-06-07T09:39:00","date_gmt":"2021-06-07T12:39:00","guid":{"rendered":"\/blog\/?p=2866"},"modified":"2023-11-22T16:28:21","modified_gmt":"2023-11-22T19:28:21","slug":"tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse","status":"publish","type":"post","link":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/","title":{"rendered":"Tipos de les\u00e3o: as diferen\u00e7as entre luxa\u00e7\u00e3o, contus\u00e3o e entorse"},"content":{"rendered":"\n<p>Queda, pequenos acidentes ou aquele mau jeito s\u00e3o normais e podem ocasionar les\u00f5es como <strong>luxa\u00e7\u00e3o, contus\u00e3o e entorse<\/strong>.<\/p>\n\n\n\n<p>Elas podem resultar em incha\u00e7o, vermelhid\u00e3o, marcas roxas ou at\u00e9 em uma situa\u00e7\u00e3o mais grave, com dor forte e a impossibilidade de mexer o membro atingido.<\/p>\n\n\n\n<p>Para minimizar os danos, \u00e9 importante entender as caracter\u00edsticas de cada <strong>tipo de les\u00e3o<\/strong>, e \u00e9 esse o prop\u00f3sito deste artigo.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 contus\u00e3o?<\/h2>\n\n\n\n<p><strong>Contus\u00e3o<\/strong> \u00e9 um tipo de <strong>les\u00e3o de impacto<\/strong>, muito comum em atletas de futebol, basquete e v\u00f4lei \u2014 mesmo os amadores, que s\u00f3 jogam de vez em quando e de forma recreativa. Normalmente, quem sofre uma contus\u00e3o sente dor e h\u00e1 incha\u00e7o e marca roxa no local da les\u00e3o.<\/p>\n\n\n\n<p>Compressas de gelo e <a href=\"https:\/\/www.panvel.com\/panvel\/medicamentos\/dor-e-contusao\/c-15?submarca=Lifar%20Arnica\" target=\"_blank\" rel=\"noreferrer noopener\">spray analg\u00e9sico<\/a> costumam melhorar a situa\u00e7\u00e3o, mas caso a dor seja persistente, a dica \u00e9 procurar um m\u00e9dico.<\/p>\n\n\n\n<p>As contus\u00f5es s\u00e3o um tipo de <strong>sangramento sob a pele<\/strong>. Na maioria das vezes, caracterizada por roxo ou vermelhid\u00e3o. Ela \u00e9 consequ\u00eancia de um golpe forte, como o cair ou colidir com um objeto grande.<\/p>\n\n\n\n<p>O aspecto vermelho ou roxo da \u00e1rea afetada se deve ao fato de a pancada quebrar pequenos vasos sangu\u00edneos, chamados capilares. Isso causa um sangramento na \u00e1rea lesionada, por baixo da pele.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Como tratar uma contus\u00e3o?<\/h3>\n\n\n\n<p>O tratamento consiste na <strong>aplica\u00e7\u00e3o imediata de gelo<\/strong> no local. Esse tipo de les\u00e3o costuma curar por conta pr\u00f3pria, dentro de alguns dias \u2014 o prazo varia dependendo do grau da contus\u00e3o.<\/p>\n\n\n\n<p>Voc\u00ea pode aplicar o gelo enquanto sentir dor ou notar incha\u00e7o na \u00e1rea lesionada. Uma<a href=\"https:\/\/www.panvel.com\/panvel\/ortopedia\/bolsa-termica\/c-1837?marca=panvel\" target=\"_blank\" rel=\"noreferrer noopener\"> <strong>bolsa t\u00e9rmica<\/strong><\/a> pode tornar mais pr\u00e1tica a aplica\u00e7\u00e3o.<\/p>\n\n\n\n<p>Se sentir necessidade, pode utilizar uma<a href=\"https:\/\/www.panvel.com\/panvel\/medicamentos\/dor-e-contusao\/dor-e-contusao\/c-31120\" target=\"_blank\" rel=\"noreferrer noopener\"> pomada<\/a>, spray analg\u00e9sico ou rem\u00e9dio para diminuir a dor.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/blog\/wp-content\/uploads\/2021\/06\/Contusao-2-1024x683.jpg\" alt=\"Contus\u00e3o, mulher aplica pomada para dor\" class=\"wp-image-2875\" srcset=\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Contusao-2-1024x683.jpg 1024w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Contusao-2-300x200.jpg 300w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Contusao-2-768x513.jpg 768w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Contusao-2-1080x721.jpg 1080w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Contusao-2-980x654.jpg 980w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Contusao-2-480x320.jpg 480w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Contusao-2.jpg 1254w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 entorse?<\/h2>\n\n\n\n<p><strong>Entorse<\/strong> \u00e9 uma <strong>les\u00e3o traum\u00e1tica<\/strong> em uma articula\u00e7\u00e3o, que pode envolver ainda distens\u00e3o (estiramento de tecido muscular nos tend\u00f5es). Sintomas comuns da entorse s\u00e3o: edema, hematoma, dor e sensibilidade ao toque.<\/p>\n\n\n\n<p>As entorses mais comuns s\u00e3o as de tornozelo, joelho e pulso, que costumam ocorrer quando \u00e9 feito um movimento em falso, brusco ou violento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Como tratar uma entorse?<\/h3>\n\n\n\n<p>Se a entorse n\u00e3o for s\u00e9ria, os primeiros socorros envolvem a aplica\u00e7\u00e3o de gelo por 15 minutos e a <strong>imobiliza\u00e7\u00e3o do local<\/strong>.<\/p>\n\n\n\n<p>O ideal \u00e9 n\u00e3o mexer no membro afetado at\u00e9 a aplica\u00e7\u00e3o do gelo e imobiliza\u00e7\u00e3o com ataduras. Mas, se houver dor forte e a dificuldade de movimenta\u00e7\u00e3o permanecer, procure um m\u00e9dico.<\/p>\n\n\n\n<p>As les\u00f5es simples s\u00e3o tratadas em at\u00e9 cinco dias, enquanto as entorses mais graves podem levar at\u00e9 um m\u00eas para curar ou at\u00e9 demandar uma cirurgia.<\/p>\n\n\n\n<p>Para melhorar a circula\u00e7\u00e3o sangu\u00ednea no local e diminuir o incha\u00e7o, voc\u00ea pode fazer suaves <a href=\"https:\/\/www.panvel.com\/panvel\/ortopedia\/alongamento\/c-1836\" target=\"_blank\" rel=\"noreferrer noopener\">alongamentos<\/a> \u2014 se doer, pare o movimento.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/blog\/wp-content\/uploads\/2021\/06\/Entorse-1-1024x683.jpg\" alt=\"Entorse, mulher com bolsa t\u00e9rmica no joelho\" class=\"wp-image-2872\" srcset=\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Entorse-1-1024x683.jpg 1024w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Entorse-1-300x200.jpg 300w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Entorse-1-768x512.jpg 768w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Entorse-1-1080x720.jpg 1080w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Entorse-1-980x653.jpg 980w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Entorse-1-480x320.jpg 480w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Entorse-1.jpg 1254w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 luxa\u00e7\u00e3o?<\/h2>\n\n\n\n<p><strong>Luxa\u00e7\u00e3o<\/strong> \u00e9 uma les\u00e3o em que ocorre o <strong>deslocamento da articula\u00e7\u00e3o<\/strong>. De todas as que abordamos aqui, \u00e9 a mais grave, e pode ocorrer no tornozelo, joelho, quadril, mand\u00edbula, dedos, ombros e cotovelos.<strong><\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Como tratar uma luxa\u00e7\u00e3o?<\/h3>\n\n\n\n<p>Assim que o deslocamento for observado, deve-se procurar um m\u00e9dico para <strong>recoloca\u00e7\u00e3o da articula\u00e7\u00e3o<\/strong> em seu local de origem.<\/p>\n\n\n\n<p>O tempo de tratamento varia de acordo com a gravidade do deslocamento, pois o local deve ficar imobilizado at\u00e9 a recupera\u00e7\u00e3o total, mas geralmente a imobiliza\u00e7\u00e3o ocorre por at\u00e9 20 dias.<\/p>\n\n\n\n<p>Caso a les\u00e3o tenha afetado nervos, vasos sangu\u00edneos ou ligamentos, pode ser necess\u00e1rio procedimento cir\u00fargico e fisioterapia.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"1024\" height=\"781\" src=\"\/blog\/wp-content\/uploads\/2021\/06\/Luxacao-1024x781.jpg\" alt=\"Luxa\u00e7\u00e3o, mulher com a perna imobilizada\" class=\"wp-image-2874\" srcset=\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Luxacao-1024x781.jpg 1024w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Luxacao-300x229.jpg 300w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Luxacao-768x586.jpg 768w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Luxacao-1080x824.jpg 1080w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Luxacao-980x748.jpg 980w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Luxacao-480x366.jpg 480w, https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Luxacao.jpg 1172w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Resumindo: quais as diferen\u00e7as entre as les\u00f5es<\/h2>\n\n\n\n<p>A <strong>diferen\u00e7a<\/strong> b\u00e1sica entre estes tr\u00eas tipos de les\u00f5es \u00e9 que a <strong>contus\u00e3o<\/strong> acontece quando o trauma gera uma les\u00e3o nos tecidos moles, a <strong>entorse<\/strong> \u00e9 quando ocorre um alongamento dos ligamentos e a luxa\u00e7\u00e3o, a mais s\u00e9ria, ocorre quando o osso se desloca da articula\u00e7\u00e3o.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que s\u00e3o os hematomas<\/h2>\n\n\n\n<p>Como estamos falando em les\u00f5es, n\u00e3o podemos deixar de falar nos hematomas. Afinal, quando eles s\u00e3o grandes, costumam assustar.<\/p>\n\n\n\n<p>Eles ocorrem em decorr\u00eancia de <strong>ac\u00famulo de sangue sob a pele<\/strong> e podem causar rigidez nos membros afetados.<\/p>\n\n\n\n<p>Se a les\u00e3o for grande, o hematoma pode ser igualmente grande. Mas, a partir do quinto dia, o normal \u00e9 que j\u00e1 comecem a desaparecer. Acompanhe a evolu\u00e7\u00e3o das marcas e, se notar algo diferente do esperado, procure um m\u00e9dico.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Consulte um m\u00e9dico<\/h2>\n\n\n\n<p>Se, depois de todos os cuidados b\u00e1sicos com primeiros socorros, voc\u00ea observar que a les\u00e3o \u00e9 grave ou est\u00e1 causando muita dor, <strong>procure um m\u00e9dico ortopedista<\/strong> imediatamente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea sabe a diferen\u00e7a entre contus\u00e3o, entorse e luxa\u00e7\u00e3o? Essas s\u00e3o algumas das les\u00f5es mais comuns. Acesse e tire suas d\u00favidas sobre elas.<\/p>\n","protected":false},"author":3,"featured_media":2870,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[171],"sponsor":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tipos de les\u00e3o: as diferen\u00e7as entre luxa\u00e7\u00e3o, contus\u00e3o e entorse | Blog Bem Panvel<\/title>\n<meta name=\"description\" content=\"Voc\u00ea sabe a diferen\u00e7a entre luxa\u00e7\u00e3o, contus\u00e3o e entorse? Essas s\u00e3o algumas das les\u00f5es mais comuns. Acesse e tire suas d\u00favidas sobre elas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tipos de les\u00e3o: as diferen\u00e7as entre luxa\u00e7\u00e3o, contus\u00e3o e entorse | Blog Bem Panvel\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea sabe a diferen\u00e7a entre luxa\u00e7\u00e3o, contus\u00e3o e entorse? Essas s\u00e3o algumas das les\u00f5es mais comuns. Acesse e tire suas d\u00favidas sobre elas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Bem Panvel\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-07T12:39:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-22T19:28:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Contusao-entorse-ou-luxacao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"717\" \/>\n\t<meta property=\"og:image:height\" content=\"423\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe Panvel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe Panvel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/\"},\"author\":{\"name\":\"Equipe Panvel\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3\"},\"headline\":\"Tipos de les\u00e3o: as diferen\u00e7as entre luxa\u00e7\u00e3o, contus\u00e3o e entorse\",\"datePublished\":\"2021-06-07T12:39:00+00:00\",\"dateModified\":\"2023-11-22T19:28:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/\"},\"wordCount\":807,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#organization\"},\"keywords\":[\"Tipos de Les\u00e3o\"],\"articleSection\":[\"Rotina de Sa\u00fade\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/\",\"url\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/\",\"name\":\"Tipos de les\u00e3o: as diferen\u00e7as entre luxa\u00e7\u00e3o, contus\u00e3o e entorse | Blog Bem Panvel\",\"isPartOf\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#website\"},\"datePublished\":\"2021-06-07T12:39:00+00:00\",\"dateModified\":\"2023-11-22T19:28:21+00:00\",\"description\":\"Voc\u00ea sabe a diferen\u00e7a entre luxa\u00e7\u00e3o, contus\u00e3o e entorse? Essas s\u00e3o algumas das les\u00f5es mais comuns. Acesse e tire suas d\u00favidas sobre elas.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.panvel.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rotina de Sa\u00fade\",\"item\":\"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tipos de les\u00e3o: as diferen\u00e7as entre luxa\u00e7\u00e3o, contus\u00e3o e entorse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#website\",\"url\":\"https:\/\/www.panvel.com\/blog\/\",\"name\":\"Blog Bem Panvel\",\"description\":\"Aqui voc\u00ea encontra conte\u00fados e dicas de sa\u00fade, beleza, bem-estar e muito mais.\",\"publisher\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.panvel.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#organization\",\"name\":\"Panvel Farm\u00e1cias\",\"url\":\"https:\/\/www.panvel.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png\",\"contentUrl\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png\",\"width\":402,\"height\":53,\"caption\":\"Panvel Farm\u00e1cias\"},\"image\":{\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3\",\"name\":\"Equipe Panvel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg\",\"contentUrl\":\"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg\",\"caption\":\"Equipe Panvel\"},\"description\":\"O Blog Bem Panvel conta com uma equipe formada por especialistas e traz para seus leitores conte\u00fados relevantes e de qualidade sobre sa\u00fade, beleza e bem-estar.\",\"url\":\"https:\/\/www.panvel.com\/blog\/author\/dimedmkt\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tipos de les\u00e3o: as diferen\u00e7as entre luxa\u00e7\u00e3o, contus\u00e3o e entorse | Blog Bem Panvel","description":"Voc\u00ea sabe a diferen\u00e7a entre luxa\u00e7\u00e3o, contus\u00e3o e entorse? Essas s\u00e3o algumas das les\u00f5es mais comuns. Acesse e tire suas d\u00favidas sobre elas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/","og_locale":"pt_BR","og_type":"article","og_title":"Tipos de les\u00e3o: as diferen\u00e7as entre luxa\u00e7\u00e3o, contus\u00e3o e entorse | Blog Bem Panvel","og_description":"Voc\u00ea sabe a diferen\u00e7a entre luxa\u00e7\u00e3o, contus\u00e3o e entorse? Essas s\u00e3o algumas das les\u00f5es mais comuns. Acesse e tire suas d\u00favidas sobre elas.","og_url":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/","og_site_name":"Blog Bem Panvel","article_published_time":"2021-06-07T12:39:00+00:00","article_modified_time":"2023-11-22T19:28:21+00:00","og_image":[{"width":717,"height":423,"url":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2021\/06\/Contusao-entorse-ou-luxacao.jpg","type":"image\/jpeg"}],"author":"Equipe Panvel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Equipe Panvel","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/#article","isPartOf":{"@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/"},"author":{"name":"Equipe Panvel","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3"},"headline":"Tipos de les\u00e3o: as diferen\u00e7as entre luxa\u00e7\u00e3o, contus\u00e3o e entorse","datePublished":"2021-06-07T12:39:00+00:00","dateModified":"2023-11-22T19:28:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/"},"wordCount":807,"commentCount":1,"publisher":{"@id":"https:\/\/www.panvel.com\/blog\/#organization"},"keywords":["Tipos de Les\u00e3o"],"articleSection":["Rotina de Sa\u00fade"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/","url":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/","name":"Tipos de les\u00e3o: as diferen\u00e7as entre luxa\u00e7\u00e3o, contus\u00e3o e entorse | Blog Bem Panvel","isPartOf":{"@id":"https:\/\/www.panvel.com\/blog\/#website"},"datePublished":"2021-06-07T12:39:00+00:00","dateModified":"2023-11-22T19:28:21+00:00","description":"Voc\u00ea sabe a diferen\u00e7a entre luxa\u00e7\u00e3o, contus\u00e3o e entorse? Essas s\u00e3o algumas das les\u00f5es mais comuns. Acesse e tire suas d\u00favidas sobre elas.","breadcrumb":{"@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/tipos-de-lesao-as-diferencas-entre-luxacao-contusao-e-entorse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.panvel.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Rotina de Sa\u00fade","item":"https:\/\/www.panvel.com\/blog\/dicas-de-saude\/"},{"@type":"ListItem","position":3,"name":"Tipos de les\u00e3o: as diferen\u00e7as entre luxa\u00e7\u00e3o, contus\u00e3o e entorse"}]},{"@type":"WebSite","@id":"https:\/\/www.panvel.com\/blog\/#website","url":"https:\/\/www.panvel.com\/blog\/","name":"Blog Bem Panvel","description":"Aqui voc\u00ea encontra conte\u00fados e dicas de sa\u00fade, beleza, bem-estar e muito mais.","publisher":{"@id":"https:\/\/www.panvel.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.panvel.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.panvel.com\/blog\/#organization","name":"Panvel Farm\u00e1cias","url":"https:\/\/www.panvel.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png","contentUrl":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2020\/10\/logo.png","width":402,"height":53,"caption":"Panvel Farm\u00e1cias"},"image":{"@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/79f5c113f9621ed83897942f6e7501e3","name":"Equipe Panvel","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.panvel.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg","contentUrl":"https:\/\/www.panvel.com\/blog\/wp-content\/uploads\/2022\/09\/blog-panvel-1.jpg","caption":"Equipe Panvel"},"description":"O Blog Bem Panvel conta com uma equipe formada por especialistas e traz para seus leitores conte\u00fados relevantes e de qualidade sobre sa\u00fade, beleza e bem-estar.","url":"https:\/\/www.panvel.com\/blog\/author\/dimedmkt\/"}]}},"_links":{"self":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts\/2866"}],"collection":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/comments?post=2866"}],"version-history":[{"count":4,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts\/2866\/revisions"}],"predecessor-version":[{"id":2877,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/posts\/2866\/revisions\/2877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/media\/2870"}],"wp:attachment":[{"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/media?parent=2866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/categories?post=2866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/tags?post=2866"},{"taxonomy":"sponsor","embeddable":true,"href":"https:\/\/www.panvel.com\/blog\/wp-json\/wp\/v2\/sponsor?post=2866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}